{"id":5982,"date":"2020-06-16T10:28:24","date_gmt":"2020-06-16T10:28:24","guid":{"rendered":"http:\/\/chateaukids.com\/?p=5982"},"modified":"2020-07-28T18:47:35","modified_gmt":"2020-07-28T18:47:35","slug":"cocuklarda-yemek-yeme-aliskanligi","status":"publish","type":"post","link":"https:\/\/chateaukids.com\/fr\/cocuklarda-yemek-yeme-aliskanligi\/","title":{"rendered":"Habitudes alimentaires chez les enfants et ce que peut faire les familles"},"content":{"rendered":"<p><a href=\"https:\/\/tr.wikipedia.org\/wiki\/Okul_%C3%B6ncesi_e%C4%9Fitim\" target=\"_blank\" rel=\"noreferrer noopener\">en p\u00e9riode pr\u00e9scolaire<\/a> La formation d\u2019habitudes nutritionnelles affecte tout le d\u00e9veloppement des enfants, notamment leur d\u00e9veloppement cognitif et physique. Lorsque les enfants atteignent l\u2019\u00e2ge de 3 ans, ils ont la capacit\u00e9 de manger seuls. Les attitudes des familles sont tr\u00e8s importantes pour les aider \u00e0 acqu\u00e9rir cette habitude. Les familles doivent leur laisser le temps de manger seuls, retirer la fourchette ou la cuill\u00e8re de leurs mains et les offrir aux enfants. <a href=\"https:\/\/tr.wikipedia.org\/wiki\/Yiyecek\" target=\"_blank\" rel=\"noreferrer noopener\">nourriture <\/a>ne devrait pas essayer de le nourrir. Durant cette p\u00e9riode, les enfants <a href=\"https:\/\/tr.wikipedia.org\/wiki\/Anoreksi\">anorexie<\/a>Des situations telles que manger moins, \u00eatre difficile et manger lentement peuvent \u00eatre observ\u00e9es. Dans de tels cas, les familles ont certaines responsabilit\u00e9s.<\/p><p><strong>Suggestions pour nos familles;<\/strong><\/p><ul class=\"wp-block-list\"><li>Certaines mesures peuvent \u00eatre prises pour \u00e9viter de manger difficilement \u00e0 un jeune \u00e2ge. Premi\u00e8rement; Les enfants doivent voir que les aliments qu\u2019ils sont cens\u00e9s manger sont \u00e9galement consomm\u00e9s par leur famille. Cela n\u2019a aucun sens que les enfants leur disent qu\u2019ils devraient manger des aliments que vous ne mangez pas. Parce que les enfants apprennent en voyant et en prenant exemple.<\/li><li>D\u00e8s le d\u00e9but des compl\u00e9ments alimentaires, poireaux etc. Les aliments doivent \u00eatre filtr\u00e9s et donn\u00e9s aux enfants, et un maximum de 2 l\u00e9gumes doivent \u00eatre m\u00e9lang\u00e9s. De cette fa\u00e7on, les enfants s\u2019habitueront au go\u00fbt de ces aliments et ne r\u00e9sisteront pas \u00e0 leur consommation. De plus, garder les aliments l\u00e9g\u00e8rement granuleux contribuera \u00e0 la formation du r\u00e9flexe de mastication et au d\u00e9veloppement des muscles buccaux.<\/li><li>Leurs assiettes ne doivent pas \u00eatre trop remplies, il faut les encourager \u00e0 manger, et lorsque leur assiette est finie, une deuxi\u00e8me assiette doit \u00eatre plac\u00e9e. Cette situation ressemble \u00e0 \u00ab\u00a0Voyons combien d\u2019assiettes vous allez manger\u00a0?\u00a0\u00bb Cela peut \u00eatre transform\u00e9 en un jeu comme.<\/li><li>Les enfants ont besoin d&#039;amour et d&#039;attention. Pendant cette p\u00e9riode, les enfants peuvent adopter des comportements tels que ne pas manger ou \u00eatre pointilleux afin d&#039;attirer l&#039;attention. S&#039;ils ne mangent pas leur nourriture, ils pensent que vous essaierez de les nourrir et de prendre soin d&#039;eux. De cette fa\u00e7on, les heures de repas augmentent. Mais vous devez \u00eatre patient \u00e0 cet \u00e9gard et ne pas le forcer \u00e0 manger vite.<\/li><li>L&#039;attitude trop d\u00e9tendue des enfants \u00e0 l&#039;\u00e9gard des heures de repas fait que ces heures de repas durent des heures. Pour cette raison, les heures de repas doivent \u00eatre limit\u00e9es, en prenant soin de ne pas les forcer \u00e0 manger rapidement. Cette heure doit \u00eatre indiqu\u00e9e \u00e0 l&#039;enfant sur une horloge et l&#039;heure de fin du repas doit \u00eatre indiqu\u00e9e (Lorsque la longue barre atteint le chiffre suivant, notre heure de repas se terminera et nous quitterons la table.)<\/li><li>S&#039;il n&#039;a pas pris son repas, il doit attendre le prochain repas et il ne doit pas \u00eatre autoris\u00e9 \u00e0 consommer des aliments tels que du chocolat, du sucre et de la malbouffe entre les repas.<\/li><li>Afin de prendre une habitude alimentaire, vous ne devez manger qu&#039;au moment des repas, vous ne devez pas regarder la t\u00e9l\u00e9vision ou des dessins anim\u00e9s pendant les repas, vous ne devez pas avoir de comprim\u00e9, etc. dans la main. les outils ne doivent pas \u00eatre donn\u00e9s.<\/li><li>En mangeant, il faut s&#039;asseoir \u00e0 table avec l&#039;enfant et manger.<\/li><\/ul><ul class=\"wp-block-list\"><li>La perte d\u2019app\u00e9tit peut en r\u00e9alit\u00e9 \u00eatre un probl\u00e8me\u00a0:<\/li><\/ul><ul class=\"wp-block-list\"><li>S&#039;il y a une forte diminution du poids corporel au cours des 1 \u00e0 2 derniers mois,<\/li><\/ul><ul class=\"wp-block-list\"><li>V\u00fccut a\u011f\u0131rl\u0131\u011f\u0131 ya\u015f\u0131na g\u00f6re ideal a\u011f\u0131rl\u0131\u011f\u0131n\u0131n %80 inden daha az ise<\/li><\/ul><p>Il faut absolument consulter un m\u00e9decin, et en cas de probl\u00e8me de poids, le traitement doit \u00eatre instaur\u00e9 sous la surveillance d&#039;un di\u00e9t\u00e9ticien et d&#039;un m\u00e9decin.<\/p><p><strong> Ch\u00e2teau Expert en Education Psychologue &amp; Conseiller Familial Merve Nazl\u0131<\/strong><\/p><p><a rel=\"noreferrer noopener\" href=\"https:\/\/chateaukids.com\/fr\/salgin-ve-psikoloji\/\" target=\"_blank\">\u00c9pid\u00e9mie et psychologie<\/a><\/p><p><a href=\"https:\/\/chateaukids.com\/fr\/ebeveynlerde-ve-cocuklarda-kaygi\/\" target=\"_blank\" rel=\"noreferrer noopener\">Que doit faire les parents lors de la p\u00e9riode d'anxi\u00e9t\u00e9 des enfants<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>La formation d\u2019habitudes alimentaires au cours de la p\u00e9riode pr\u00e9scolaire affecte tout le d\u00e9veloppement des enfants, notamment leur d\u00e9veloppement cognitif et physique.<\/p>","protected":false},"author":1,"featured_media":5984,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[1],"tags":[122,123,124,125,126],"class_list":["post-5982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-genel","tag-okul-oncesi-donem","tag-cocuklarda-istahsizlik","tag-cocuk-gelisimi","tag-cocuklarda-bilissel-gelisim","tag-cocuklarda-fiziksel-gelisim"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c7ocuklarda Yemek Yeme Al\u0131\u015fkanl\u0131\u011f\u0131 | Ch\u00e2teauKIDS<\/title>\n<meta name=\"description\" content=\"Okul \u00f6ncesi d\u00f6nemde beslenme al\u0131\u015fkanl\u0131\u011f\u0131n\u0131n olu\u015fmas\u0131. \u0130\u015ftahs\u0131zl\u0131k, az yemek yeme, yemek se\u00e7me ve yava\u015f yeme gibi durumlara \u00e7\u00f6z\u00fcmler. Aileler ne yapmal\u0131?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chateaukids.com\/fr\/cocuklarda-yemek-yeme-aliskanligi\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c7ocuklarda Yemek Yeme Al\u0131\u015fkanl\u0131\u011f\u0131 | Ch\u00e2teauKIDS\" \/>\n<meta property=\"og:description\" content=\"Okul \u00f6ncesi d\u00f6nemde beslenme al\u0131\u015fkanl\u0131\u011f\u0131n\u0131n olu\u015fmas\u0131. \u0130\u015ftahs\u0131zl\u0131k, az yemek yeme, yemek se\u00e7me ve yava\u015f yeme gibi durumlara \u00e7\u00f6z\u00fcmler. Aileler ne yapmal\u0131?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chateaukids.com\/fr\/cocuklarda-yemek-yeme-aliskanligi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ch\u00e2teauKIDS\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-16T10:28:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-28T18:47:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chateaukids.com\/wp-content\/uploads\/2020\/06\/crop-children-with-fresh-red-pepper-and-other-vegetables-3984724.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chateau E\u011fitim\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chateau E\u011fitim\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/chateaukids.com\/cocuklarda-yemek-yeme-aliskanligi\/\",\"url\":\"https:\/\/chateaukids.com\/cocuklarda-yemek-yeme-aliskanligi\/\",\"name\":\"\u00c7ocuklarda Yemek Yeme Al\u0131\u015fkanl\u0131\u011f\u0131 | Ch\u00e2teauKIDS\",\"isPartOf\":{\"@id\":\"https:\/\/chateaukids.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/chateaukids.com\/cocuklarda-yemek-yeme-aliskanligi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/chateaukids.com\/cocuklarda-yemek-yeme-aliskanligi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/chateaukids.com\/wp-content\/uploads\/2020\/06\/crop-children-with-fresh-red-pepper-and-other-vegetables-3984724.jpg\",\"datePublished\":\"2020-06-16T10:28:24+00:00\",\"dateModified\":\"2020-07-28T18:47:35+00:00\",\"author\":{\"@id\":\"https:\/\/chateaukids.com\/#\/schema\/person\/e420fb4db550e89aafd2392f9481c1bd\"},\"description\":\"Okul \u00f6ncesi d\u00f6nemde beslenme al\u0131\u015fkanl\u0131\u011f\u0131n\u0131n olu\u015fmas\u0131. \u0130\u015ftahs\u0131zl\u0131k, az yemek yeme, yemek se\u00e7me ve yava\u015f yeme gibi durumlara \u00e7\u00f6z\u00fcmler. Aileler ne yapmal\u0131?\",\"breadcrumb\":{\"@id\":\"https:\/\/chateaukids.com\/cocuklarda-yemek-yeme-aliskanligi\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/chateaukids.com\/cocuklarda-yemek-yeme-aliskanligi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/chateaukids.com\/cocuklarda-yemek-yeme-aliskanligi\/#primaryimage\",\"url\":\"https:\/\/chateaukids.com\/wp-content\/uploads\/2020\/06\/crop-children-with-fresh-red-pepper-and-other-vegetables-3984724.jpg\",\"contentUrl\":\"https:\/\/chateaukids.com\/wp-content\/uploads\/2020\/06\/crop-children-with-fresh-red-pepper-and-other-vegetables-3984724.jpg\",\"width\":2000,\"height\":1333,\"caption\":\"okul \u00f6ncesi d\u00f6nemde \u00e7ocuklar\u0131n beslenme al\u0131\u015fkanl\u0131klar\u0131 ve ailelerin yapabilecekleri\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/chateaukids.com\/cocuklarda-yemek-yeme-aliskanligi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Ana sayfa\",\"item\":\"https:\/\/chateaukids.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c7ocuklarda Yemek Yeme Al\u0131\u015fkanl\u0131\u011f\u0131\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/chateaukids.com\/#website\",\"url\":\"https:\/\/chateaukids.com\/\",\"name\":\"Ch\u00e2teauKIDS\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/chateaukids.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/chateaukids.com\/#\/schema\/person\/e420fb4db550e89aafd2392f9481c1bd\",\"name\":\"Chateau E\u011fitim\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/chateaukids.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/chateaukids.com\/wp-content\/litespeed\/avatar\/4ef83b571816d27c0588df89fc130832.jpg?ver=1778605177\",\"contentUrl\":\"https:\/\/chateaukids.com\/wp-content\/litespeed\/avatar\/4ef83b571816d27c0588df89fc130832.jpg?ver=1778605177\",\"caption\":\"Chateau E\u011fitim\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c7ocuklarda Yemek Yeme Al\u0131\u015fkanl\u0131\u011f\u0131 | Ch\u00e2teauKIDS","description":"Okul \u00f6ncesi d\u00f6nemde beslenme al\u0131\u015fkanl\u0131\u011f\u0131n\u0131n olu\u015fmas\u0131. \u0130\u015ftahs\u0131zl\u0131k, az yemek yeme, yemek se\u00e7me ve yava\u015f yeme gibi durumlara \u00e7\u00f6z\u00fcmler. Aileler ne yapmal\u0131?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chateaukids.com\/fr\/cocuklarda-yemek-yeme-aliskanligi\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c7ocuklarda Yemek Yeme Al\u0131\u015fkanl\u0131\u011f\u0131 | Ch\u00e2teauKIDS","og_description":"Okul \u00f6ncesi d\u00f6nemde beslenme al\u0131\u015fkanl\u0131\u011f\u0131n\u0131n olu\u015fmas\u0131. \u0130\u015ftahs\u0131zl\u0131k, az yemek yeme, yemek se\u00e7me ve yava\u015f yeme gibi durumlara \u00e7\u00f6z\u00fcmler. Aileler ne yapmal\u0131?","og_url":"https:\/\/chateaukids.com\/fr\/cocuklarda-yemek-yeme-aliskanligi\/","og_site_name":"Ch\u00e2teauKIDS","article_published_time":"2020-06-16T10:28:24+00:00","article_modified_time":"2020-07-28T18:47:35+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/chateaukids.com\/wp-content\/uploads\/2020\/06\/crop-children-with-fresh-red-pepper-and-other-vegetables-3984724.jpg","type":"image\/jpeg"}],"author":"Chateau E\u011fitim","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Chateau E\u011fitim","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/chateaukids.com\/cocuklarda-yemek-yeme-aliskanligi\/","url":"https:\/\/chateaukids.com\/cocuklarda-yemek-yeme-aliskanligi\/","name":"\u00c7ocuklarda Yemek Yeme Al\u0131\u015fkanl\u0131\u011f\u0131 | Ch\u00e2teauKIDS","isPartOf":{"@id":"https:\/\/chateaukids.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/chateaukids.com\/cocuklarda-yemek-yeme-aliskanligi\/#primaryimage"},"image":{"@id":"https:\/\/chateaukids.com\/cocuklarda-yemek-yeme-aliskanligi\/#primaryimage"},"thumbnailUrl":"https:\/\/chateaukids.com\/wp-content\/uploads\/2020\/06\/crop-children-with-fresh-red-pepper-and-other-vegetables-3984724.jpg","datePublished":"2020-06-16T10:28:24+00:00","dateModified":"2020-07-28T18:47:35+00:00","author":{"@id":"https:\/\/chateaukids.com\/#\/schema\/person\/e420fb4db550e89aafd2392f9481c1bd"},"description":"Okul \u00f6ncesi d\u00f6nemde beslenme al\u0131\u015fkanl\u0131\u011f\u0131n\u0131n olu\u015fmas\u0131. \u0130\u015ftahs\u0131zl\u0131k, az yemek yeme, yemek se\u00e7me ve yava\u015f yeme gibi durumlara \u00e7\u00f6z\u00fcmler. Aileler ne yapmal\u0131?","breadcrumb":{"@id":"https:\/\/chateaukids.com\/cocuklarda-yemek-yeme-aliskanligi\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chateaukids.com\/cocuklarda-yemek-yeme-aliskanligi\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/chateaukids.com\/cocuklarda-yemek-yeme-aliskanligi\/#primaryimage","url":"https:\/\/chateaukids.com\/wp-content\/uploads\/2020\/06\/crop-children-with-fresh-red-pepper-and-other-vegetables-3984724.jpg","contentUrl":"https:\/\/chateaukids.com\/wp-content\/uploads\/2020\/06\/crop-children-with-fresh-red-pepper-and-other-vegetables-3984724.jpg","width":2000,"height":1333,"caption":"okul \u00f6ncesi d\u00f6nemde \u00e7ocuklar\u0131n beslenme al\u0131\u015fkanl\u0131klar\u0131 ve ailelerin yapabilecekleri"},{"@type":"BreadcrumbList","@id":"https:\/\/chateaukids.com\/cocuklarda-yemek-yeme-aliskanligi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Ana sayfa","item":"https:\/\/chateaukids.com\/"},{"@type":"ListItem","position":2,"name":"\u00c7ocuklarda Yemek Yeme Al\u0131\u015fkanl\u0131\u011f\u0131"}]},{"@type":"WebSite","@id":"https:\/\/chateaukids.com\/#website","url":"https:\/\/chateaukids.com\/","name":"Ch\u00e2teauKIDS","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chateaukids.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/chateaukids.com\/#\/schema\/person\/e420fb4db550e89aafd2392f9481c1bd","name":"Chateau E\u011fitim","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/chateaukids.com\/#\/schema\/person\/image\/","url":"https:\/\/chateaukids.com\/wp-content\/litespeed\/avatar\/4ef83b571816d27c0588df89fc130832.jpg?ver=1778605177","contentUrl":"https:\/\/chateaukids.com\/wp-content\/litespeed\/avatar\/4ef83b571816d27c0588df89fc130832.jpg?ver=1778605177","caption":"Chateau E\u011fitim"}}]}},"_links":{"self":[{"href":"https:\/\/chateaukids.com\/fr\/wp-json\/wp\/v2\/posts\/5982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chateaukids.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chateaukids.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chateaukids.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chateaukids.com\/fr\/wp-json\/wp\/v2\/comments?post=5982"}],"version-history":[{"count":2,"href":"https:\/\/chateaukids.com\/fr\/wp-json\/wp\/v2\/posts\/5982\/revisions"}],"predecessor-version":[{"id":5986,"href":"https:\/\/chateaukids.com\/fr\/wp-json\/wp\/v2\/posts\/5982\/revisions\/5986"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chateaukids.com\/fr\/wp-json\/wp\/v2\/media\/5984"}],"wp:attachment":[{"href":"https:\/\/chateaukids.com\/fr\/wp-json\/wp\/v2\/media?parent=5982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chateaukids.com\/fr\/wp-json\/wp\/v2\/categories?post=5982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chateaukids.com\/fr\/wp-json\/wp\/v2\/tags?post=5982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}